{"id":3185,"count":0,"description":"","link":"http:\/\/www.lumbinilive.com\/blog\/tag\/thermocouple-sensor-49b2-5e0f27\/","name":"Thermocouple Sensor","slug":"thermocouple-sensor-49b2-5e0f27","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"http:\/\/www.lumbinilive.com\/blog\/wp-json\/wp\/v2\/tags\/3185","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.lumbinilive.com\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"http:\/\/www.lumbinilive.com\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"http:\/\/www.lumbinilive.com\/blog\/wp-json\/wp\/v2\/posts?tags=3185"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}